{"id":12371,"date":"2021-09-03T14:44:22","date_gmt":"2021-09-03T14:44:22","guid":{"rendered":"https:\/\/pergaminho.design\/?post_type=portfolio&#038;p=12371"},"modified":"2026-03-27T10:36:08","modified_gmt":"2026-03-27T10:36:08","slug":"clara-diego","status":"publish","type":"portfolio","link":"https:\/\/pergaminho.design\/es\/cartera\/clara-diego\/","title":{"rendered":"Clara y Diego"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"12371\" class=\"elementor elementor-12371\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-8291443 e-flex e-con-boxed e-con e-parent\" data-id=\"8291443\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-1462729 elementor-hidden-desktop e-flex e-con-boxed e-con e-child\" data-id=\"1462729\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bad8513 elementor-widget elementor-widget-heading\" data-id=\"bad8513\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Clara y Diego<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbe0d02 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"bbe0d02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Iglesia de San Sebasti\u00e1n, Faro \u2014 Febrero de 2022<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-93a761b elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"93a761b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-ef0fe98\" data-id=\"ef0fe98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-730eba1 elementor-widget elementor-widget-image\" data-id=\"730eba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1630\" height=\"1075\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-01.jpg\" class=\"attachment-full size-full wp-image-12392\" alt=\"Invitaci\u00f3n de boda minimalista en color beige con un estilo desgastado y una cinta de lino beige.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-01.jpg 1630w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-01-150x99.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-01-1000x660.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-01-300x198.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-01-1024x675.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-01-768x507.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-01-1536x1013.jpg 1536w\" sizes=\"auto, (max-width: 1630px) 100vw, 1630px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bec30c4 elementor-widget elementor-widget-image\" data-id=\"bec30c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1631\" height=\"1075\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-02.jpg\" class=\"attachment-full size-full wp-image-12393\" alt=\"Invitaci\u00f3n de boda minimalista con efecto rasgado y detalles en color beige.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-02.jpg 1631w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-02-150x99.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-02-1000x659.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-02-300x198.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-02-1024x675.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-02-768x506.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-02-1536x1012.jpg 1536w\" sizes=\"auto, (max-width: 1631px) 100vw, 1631px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f088087 elementor-widget elementor-widget-image\" data-id=\"f088087\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1631\" height=\"1076\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-05.jpg\" class=\"attachment-full size-full wp-image-12396\" alt=\"Tarjeta de mesa y marcador de sitio de estilo minimalista con efecto rasgado, presentados en un sobre beige.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-05.jpg 1631w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-05-150x99.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-05-1000x660.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-05-300x198.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-05-1024x676.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-05-768x507.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-05-1536x1013.jpg 1536w\" sizes=\"auto, (max-width: 1631px) 100vw, 1631px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb935dd e-con-full e-flex e-con e-parent\" data-id=\"bb935dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6072f65 e-con-full e-flex e-con e-child\" data-id=\"6072f65\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a09e60f elementor-widget elementor-widget-image\" data-id=\"a09e60f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"791\" height=\"1024\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-03-791x1024.jpg\" class=\"attachment-large size-large wp-image-12394\" alt=\"Invitaci\u00f3n de boda color beige con un acabado minimalista y rasgado, y una cinta de lino beige.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-03-791x1024.jpg 791w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-03-150x194.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-03-232x300.jpg 232w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-03-768x995.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-03.jpg 830w\" sizes=\"auto, (max-width: 791px) 100vw, 791px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-daa7c03 e-con-full e-flex e-con e-child\" data-id=\"daa7c03\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2158fb elementor-widget elementor-widget-image\" data-id=\"a2158fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"792\" height=\"1024\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-04-792x1024.jpg\" class=\"attachment-large size-large wp-image-12395\" alt=\"Tarjeta de mesa color beige con un efecto desgastado minimalista y una cinta de lino beige.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-04-792x1024.jpg 792w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-04-150x194.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-04-232x300.jpg 232w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-04-768x994.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-04.jpg 831w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83f5a3c elementor-widget elementor-widget-image\" data-id=\"83f5a3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1631\" height=\"1076\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-06.jpg\" class=\"attachment-full size-full wp-image-12397\" alt=\"Invitaci\u00f3n de boda y tarjeta de mesa con sobre blanco con efecto rasgado y detalles en color beige.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-06.jpg 1631w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-06-150x99.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-06-1000x660.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-06-300x198.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-06-1024x676.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-06-768x507.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-06-1536x1013.jpg 1536w\" sizes=\"auto, (max-width: 1631px) 100vw, 1631px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-601426b elementor-widget elementor-widget-image\" data-id=\"601426b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1631\" height=\"1076\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-07.jpg\" class=\"attachment-full size-full wp-image-12398\" alt=\"Invitaci\u00f3n de boda, tarjeta de mesa y men\u00fa con sobre blanco con efecto rasgado y detalles en color beige.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-07.jpg 1631w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-07-150x99.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-07-1000x660.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-07-300x198.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-07-1024x676.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-07-768x507.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-07-1536x1013.jpg 1536w\" sizes=\"auto, (max-width: 1631px) 100vw, 1631px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34e2866 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"34e2866\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7dab5ca e-con-full e-flex e-con e-child\" data-id=\"7dab5ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd18050 elementor-widget elementor-widget-image\" data-id=\"cd18050\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1277\" height=\"1079\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586.jpg\" class=\"attachment-full size-full wp-image-22538\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586.jpg 1277w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-150x127.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-1000x845.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-300x253.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-1024x865.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-768x649.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-14x12.jpg 14w\" sizes=\"auto, (max-width: 1277px) 100vw, 1277px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7a6cee e-con-full e-flex e-con e-child\" data-id=\"c7a6cee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f7b410 elementor-widget elementor-widget-heading\" data-id=\"8f7b410\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agenda una reuni\u00f3n y cu\u00e9ntanos un poco m\u00e1s sobre tu historia.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce71a90 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"ce71a90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El matrimonio es uno de los momentos m\u00e1s importantes y, como tal, merece todo el esfuerzo y la dedicaci\u00f3n. Si a\u00fan tienes dudas y necesitas ayuda, cont\u00e1ctanos y programa una reuni\u00f3n para que podamos asesorarte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-1f90dcb e-flex e-con-boxed e-con e-child\" data-id=\"1f90dcb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d1041b elementor-widget__width-auto elementor-align-left elementor-widget elementor-widget-button\" data-id=\"0d1041b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pergaminho.design\/es\/solicita-un-presupuesto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SOLICITE UN PRESUPUESTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a81b057 elementor-widget__width-auto elementor-align-left elementor-widget elementor-widget-button\" data-id=\"a81b057\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pergaminho.design\/es\/programar-una-reunion\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PROGRAMAR UNA REUNI\u00d3N<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dddefff wd-elementor-sticky-column wd_sticky_offset_150\" data-id=\"dddefff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95f1beb elementor-hidden-mobile elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"95f1beb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Clara y Diego<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-151fbfa elementor-hidden-mobile elementor-hidden-tablet color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"151fbfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Iglesia de San Sebasti\u00e1n, Faro \u2014 Febrero de 2022<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff2b184 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"ff2b184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una invitaci\u00f3n minimalista no es s\u00f3lo una invitaci\u00f3n \"sencilla\", es importante que el estilo est\u00e9 bien elaborado, sin excesos, para que transmita elegancia de forma sencilla.<\/p><p>Es natural que cuando las parejas buscan este tipo de estilo, surjan preguntas, la m\u00e1s com\u00fan de las cuales es: \u00bfc\u00f3mo est\u00e1 compuesta la invitaci\u00f3n de boda minimalista? La caracter\u00edstica principal de una invitaci\u00f3n de boda minimalista suele ser su aspecto limpio, pero lo que realmente da vida a la invitaci\u00f3n son todos los detalles, como el papel utilizado o las piezas complementarias.<\/p><p>Otra pregunta que puede surgir es: \u00bfc\u00f3mo puedo estar seguro de que tiene sentido elegir el estilo minimal para mi boda? Este estilo se puede utilizar en diferentes tipos de bodas, con diferentes temas y personalidades, como bodas en la playa o incluso bodas m\u00e1s urbanas, siempre que se mantenga limpio y elegante, sin excesos.\u00a0<\/p><p>Nuestra pareja Clara y Diego eligi\u00f3 una invitaci\u00f3n de boda de estilo geom\u00e9trico y cl\u00e1sico. En este caso, la invitaci\u00f3n y su papeler\u00eda son un reflejo de la pasi\u00f3n de la pareja por la arquitectura cl\u00e1sica, que se manifiesta en un marco elegante y minimalista y en la elecci\u00f3n de una tipograf\u00eda distintiva y refinada. Las piezas de la boda est\u00e1n marcadas por tonos suaves, rosa permanente y un color bronce que da vida a los elementos geom\u00e9tricos y crea un llamativo contraste en el papel de algod\u00f3n que re\u00fane todos estos elementos en una invitaci\u00f3n perfecta.<\/p><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f40b17 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"9f40b17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><th>Estilo de dise\u00f1o<\/th><td style=\"text-align: right;\">Invitaciones minimalistas<\/td><\/tr><tr><th>Tipo de papel<\/th><td style=\"text-align: right;\">Algod\u00f3n<\/td><\/tr><tr><th>Extras<\/th><td style=\"text-align: right;\">Sobre impreso<\/td><\/tr><tr><th>Sobre<\/th><td style=\"text-align: right;\">Acabado rasgado<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-dbe8757 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dbe8757\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-110118a\" data-id=\"110118a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca81520 elementor-widget elementor-widget-wd_social_buttons\" data-id=\"ca81520\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_social_buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wd-social-icons wd-style-colored wd-size-small social-share wd-shape-circle color-scheme-dark text-left\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/pergaminho.design\/es\/cartera\/clara-diego\/\" target=\"_blank\" class=\"wd-social-icon social-facebook\" aria-label=\"Enlace social de Facebook\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/x.com\/share?url=https:\/\/pergaminho.design\/es\/cartera\/clara-diego\/\" target=\"_blank\" class=\"wd-social-icon social-twitter\" aria-label=\"Enlace social X\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/pergaminho.design\/es\/cartera\/clara-diego\/&#038;media=https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/09\/ClaraeDiego_Website-01.jpg&#038;description=Clara%20%26%23038%3B%20Diego\" target=\"_blank\" class=\"wd-social-icon social-pinterest\" aria-label=\"Enlace social a Pinterest\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https:\/\/pergaminho.design\/es\/cartera\/clara-diego\/\" target=\"_blank\" class=\"wd-social-icon social-linkedin\" aria-label=\"Enlace social de LinkedIn\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-73d709b e-con-full elementor-hidden-desktop e-flex e-con e-parent\" data-id=\"73d709b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d705ef6 e-con-full e-flex e-con e-child\" data-id=\"d705ef6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d69337 elementor-widget elementor-widget-image\" data-id=\"1d69337\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1277\" height=\"1079\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586.jpg\" class=\"attachment-full size-full wp-image-22538\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586.jpg 1277w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-150x127.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-1000x845.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-300x253.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-1024x865.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-768x649.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-14x12.jpg 14w\" sizes=\"auto, (max-width: 1277px) 100vw, 1277px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f44534 e-con-full e-flex e-con e-child\" data-id=\"6f44534\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bbbf3d elementor-widget elementor-widget-heading\" data-id=\"9bbbf3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agenda una reuni\u00f3n y cu\u00e9ntanos un poco m\u00e1s sobre tu historia.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2cdd42 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"e2cdd42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El matrimonio es uno de los momentos m\u00e1s importantes y, como tal, merece todo el esfuerzo y la dedicaci\u00f3n. Si a\u00fan tienes dudas y necesitas ayuda, cont\u00e1ctanos y programa una reuni\u00f3n para que podamos asesorarte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-1e8d5ac e-flex e-con-boxed e-con e-child\" data-id=\"1e8d5ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-142325d elementor-widget__width-auto elementor-align-left elementor-widget elementor-widget-button\" data-id=\"142325d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pergaminho.design\/es\/solicita-un-presupuesto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SOLICITE UN PRESUPUESTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-827f191 elementor-widget__width-auto elementor-align-left elementor-widget elementor-widget-button\" data-id=\"827f191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pergaminho.design\/es\/programar-una-reunion\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PROGRAMAR UNA REUNI\u00d3N<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Iglesia de San Sebasti\u00e1n de Clara y Diego, Faro \u2015 Febrero de 2022 Concierte una cita y cu\u00e9ntenos un poco m\u00e1s sobre usted.<\/p>","protected":false},"featured_media":12392,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","project-cat":[251],"class_list":["post-12371","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","project-cat-minimalistas"],"acf":[],"_links":{"self":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/portfolio\/12371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/comments?post=12371"}],"version-history":[{"count":5,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/portfolio\/12371\/revisions"}],"predecessor-version":[{"id":36766,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/portfolio\/12371\/revisions\/36766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/media\/12392"}],"wp:attachment":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/media?parent=12371"}],"wp:term":[{"taxonomy":"project-cat","embeddable":true,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/project-cat?post=12371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}