{"id":10588,"date":"2021-04-11T09:15:14","date_gmt":"2021-04-11T09:15:14","guid":{"rendered":"http:\/\/pergaminho-design.local\/?post_type=portfolio&#038;p=10588"},"modified":"2026-03-27T10:39:25","modified_gmt":"2026-03-27T10:39:25","slug":"paula-sergio","status":"publish","type":"portfolio","link":"https:\/\/pergaminho.design\/es\/cartera\/paula-sergio\/","title":{"rendered":"Paula y Sergio"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10588\" class=\"elementor elementor-10588\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-de9f566 e-flex e-con-boxed e-con e-parent\" data-id=\"de9f566\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-2d9ecba elementor-hidden-desktop e-flex e-con-boxed e-con e-child\" data-id=\"2d9ecba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9bf13e elementor-widget elementor-widget-heading\" data-id=\"f9bf13e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Paula y Sergio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d205c00 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"d205c00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Quinta Redolho de Cima \u2013 mayo de 2022<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-1abcb43 elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1abcb43\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-bb5eb98\" data-id=\"bb5eb98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d66ffae elementor-widget elementor-widget-image\" data-id=\"d66ffae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1691\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-01-scaled-1.jpg\" class=\"attachment-full size-full wp-image-9433\" alt=\"Invitaci\u00f3n de boda con detalles verdes e hilo beige.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-01-scaled-1.jpg 2560w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-01-scaled-1-150x99.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-01-scaled-1-1000x661.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-01-scaled-1-300x198.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-01-scaled-1-1024x676.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-01-scaled-1-768x507.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-01-scaled-1-1536x1015.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-01-scaled-1-2048x1353.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95bbebf elementor-widget elementor-widget-image\" data-id=\"95bbebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1691\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-02-scaled-1.jpg\" class=\"attachment-full size-full wp-image-9434\" alt=\"Invitaci\u00f3n de boda con detalles verdes y caja de madera.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-02-scaled-1.jpg 2560w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-02-scaled-1-150x99.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-02-scaled-1-1000x661.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-02-scaled-1-300x198.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-02-scaled-1-1024x676.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-02-scaled-1-768x507.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-02-scaled-1-1536x1015.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-02-scaled-1-2048x1353.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66cec04 elementor-widget elementor-widget-image\" data-id=\"66cec04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1691\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-03-scaled-1.jpg\" class=\"attachment-full size-full wp-image-9438\" alt=\"Invitaci\u00f3n de boda con detalles tipogr\u00e1ficos en verde.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-03-scaled-1.jpg 2560w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-03-scaled-1-150x99.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-03-scaled-1-1000x661.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-03-scaled-1-300x198.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-03-scaled-1-1024x676.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-03-scaled-1-768x507.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-03-scaled-1-1536x1015.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-03-scaled-1-2048x1353.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67f7907 e-con-full e-flex e-con e-parent\" data-id=\"67f7907\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b75950f e-con-full e-flex e-con e-child\" data-id=\"b75950f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cf8c57 elementor-widget elementor-widget-image\" data-id=\"6cf8c57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1319\" height=\"1789\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-04.jpg\" class=\"attachment-full size-full wp-image-9439\" alt=\"Invitaci\u00f3n de boda con detalles tipogr\u00e1ficos en verde.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-04.jpg 1319w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-04-150x203.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-04-1000x1356.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-04-221x300.jpg 221w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-04-755x1024.jpg 755w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-04-768x1042.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-04-1132x1536.jpg 1132w\" sizes=\"auto, (max-width: 1319px) 100vw, 1319px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c9d8d8 e-con-full e-flex e-con e-child\" data-id=\"1c9d8d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-872029e elementor-widget elementor-widget-image\" data-id=\"872029e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1319\" height=\"1789\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-05.jpg\" class=\"attachment-full size-full wp-image-9440\" alt=\"Invitaci\u00f3n de boda con detalles tipogr\u00e1ficos en verde.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-05.jpg 1319w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-05-150x203.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-05-1000x1356.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-05-221x300.jpg 221w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-05-755x1024.jpg 755w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-05-768x1042.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-05-1132x1536.jpg 1132w\" sizes=\"auto, (max-width: 1319px) 100vw, 1319px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64f87d5 elementor-widget elementor-widget-image\" data-id=\"64f87d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1691\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-06-scaled-1.jpg\" class=\"attachment-full size-full wp-image-9441\" alt=\"Invitaci\u00f3n de boda con detalles tipogr\u00e1ficos en verde.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-06-scaled-1.jpg 2560w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-06-scaled-1-150x99.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-06-scaled-1-1000x661.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-06-scaled-1-300x198.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-06-scaled-1-1024x676.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-06-scaled-1-768x507.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-06-scaled-1-1536x1015.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-06-scaled-1-2048x1353.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b71ceb6 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"b71ceb6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3d19619 e-con-full e-flex e-con e-child\" data-id=\"3d19619\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dd1994 elementor-widget elementor-widget-image\" data-id=\"2dd1994\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1277\" height=\"1079\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586.jpg\" class=\"attachment-full size-full wp-image-22538\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586.jpg 1277w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-150x127.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-1000x845.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-300x253.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-1024x865.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-768x649.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-14x12.jpg 14w\" sizes=\"auto, (max-width: 1277px) 100vw, 1277px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25d91a6 e-con-full e-flex e-con e-child\" data-id=\"25d91a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d41d22 elementor-widget elementor-widget-heading\" data-id=\"1d41d22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agenda una reuni\u00f3n y cu\u00e9ntanos un poco m\u00e1s sobre tu historia.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81e5937 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"81e5937\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El matrimonio es uno de los momentos m\u00e1s importantes y, como tal, merece todo el esfuerzo y la dedicaci\u00f3n. Si a\u00fan tienes dudas y necesitas ayuda, cont\u00e1ctanos y programa una reuni\u00f3n para que podamos asesorarte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-41f4a5b e-flex e-con-boxed e-con e-child\" data-id=\"41f4a5b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16addba elementor-widget__width-auto elementor-align-left elementor-widget elementor-widget-button\" data-id=\"16addba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pergaminho.design\/es\/solicita-un-presupuesto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SOLICITE UN PRESUPUESTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f7f669 elementor-widget__width-auto elementor-align-left elementor-widget elementor-widget-button\" data-id=\"1f7f669\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pergaminho.design\/es\/programar-una-reunion\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PROGRAMAR UNA REUNI\u00d3N<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-89ed634 wd-elementor-sticky-column wd_sticky_offset_150\" data-id=\"89ed634\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01bfca2 elementor-hidden-mobile elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"01bfca2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Paula y Sergio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce11bcc elementor-hidden-mobile elementor-hidden-tablet color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"ce11bcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Quinta Redolho de Cima \u2013 mayo de 2022<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b03dc52 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"b03dc52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa boda es un momento de celebraci\u00f3n y alegr\u00eda para los novios y todos sus invitados, pero no siempre tiene por qu\u00e9 ser compleja y exuberante. Cada vez son m\u00e1s las parejas que optan por un estilo sencillo, elegante y minimalista y trasladan este estilo a su papeler\u00eda nupcial. La invitaci\u00f3n de boda minimalista es un dise\u00f1o elegante, limpio y extremadamente vers\u00e1til. Suele ser elegido por parejas m\u00e1s sencillas y relajadas. Pero no te hagas a la idea de que el estilo minimalista es menos especial, el secreto est\u00e1 en la forma de realizar el material gr\u00e1fico. Los diferentes estampados y detalles pueden marcar la diferencia y convertir tu invitaci\u00f3n de boda en una acorde con tu estilo sin dejar de ser especial e inolvidable. Las invitaciones de boda minimalistas se componen de detalles limpios y neutros y siempre se prefiere que los colores utilizados sean claros. \n\nComo es el caso de Paula y S\u00e9rgio, que optaron por una invitaci\u00f3n minimalista y delicada que sobrevive a cualquier clima y nos da una sensaci\u00f3n de tranquilidad con el color verde claro de los elementos y el blanco del papel. Esta papeler\u00eda incluye invitaciones especiales para los padrinos en una caja de madera. En esta papeler\u00eda, utilizamos un tipo de letra con l\u00edneas finas que coinciden con el registro de la ilustraci\u00f3n y mantienen un registro minimalista y un car\u00e1cter artesanal. Todas las piezas est\u00e1n decoradas una a una con una peque\u00f1a rama de olivo que se repite como un acento muy importante y es el tema de la fiesta de boda.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2d213d color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"b2d213d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><th>Estilo de dise\u00f1o<\/th><td style=\"text-align: right;\">Invitaciones minimalistas<\/td><\/tr><tr><th>Tipo de papel<\/th><td style=\"text-align: right;\">Algod\u00f3n<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-14f6be2 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14f6be2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9019e9\" data-id=\"e9019e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a690f8b elementor-widget elementor-widget-wd_social_buttons\" data-id=\"a690f8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_social_buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wd-social-icons wd-style-colored wd-size-small social-share wd-shape-circle color-scheme-dark text-left\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/pergaminho.design\/es\/cartera\/paula-sergio\/\" target=\"_blank\" class=\"wd-social-icon social-facebook\" aria-label=\"Enlace social de Facebook\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/x.com\/share?url=https:\/\/pergaminho.design\/es\/cartera\/paula-sergio\/\" target=\"_blank\" class=\"wd-social-icon social-twitter\" aria-label=\"Enlace social X\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/pergaminho.design\/es\/cartera\/paula-sergio\/&#038;media=https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/02\/PaulaeSergio_Website-02-scaled-1.jpg&#038;description=Paula%20%26%23038%3B%20S%C3%A9rgio\" target=\"_blank\" class=\"wd-social-icon social-pinterest\" aria-label=\"Enlace social a Pinterest\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https:\/\/pergaminho.design\/es\/cartera\/paula-sergio\/\" target=\"_blank\" class=\"wd-social-icon social-linkedin\" aria-label=\"Enlace social de LinkedIn\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-d9defd9 e-con-full elementor-hidden-desktop e-flex e-con e-parent\" data-id=\"d9defd9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-53c1809 e-con-full e-flex e-con e-child\" data-id=\"53c1809\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a0130b elementor-widget elementor-widget-image\" data-id=\"3a0130b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1277\" height=\"1079\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586.jpg\" class=\"attachment-full size-full wp-image-22538\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586.jpg 1277w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-150x127.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-1000x845.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-300x253.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-1024x865.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-768x649.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-14x12.jpg 14w\" sizes=\"auto, (max-width: 1277px) 100vw, 1277px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a22b66 e-con-full e-flex e-con e-child\" data-id=\"5a22b66\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba3be5b elementor-widget elementor-widget-heading\" data-id=\"ba3be5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agenda una reuni\u00f3n y cu\u00e9ntanos un poco m\u00e1s sobre tu historia.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-391795b color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"391795b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El matrimonio es uno de los momentos m\u00e1s importantes y, como tal, merece todo el esfuerzo y la dedicaci\u00f3n. Si a\u00fan tienes dudas y necesitas ayuda, cont\u00e1ctanos y programa una reuni\u00f3n para que podamos asesorarte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-4e9a019 e-flex e-con-boxed e-con e-child\" data-id=\"4e9a019\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3068168 elementor-widget__width-auto elementor-align-left elementor-widget elementor-widget-button\" data-id=\"3068168\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pergaminho.design\/es\/solicita-un-presupuesto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SOLICITE UN PRESUPUESTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8953ba elementor-widget__width-auto elementor-align-left elementor-widget elementor-widget-button\" data-id=\"a8953ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pergaminho.design\/es\/programar-una-reunion\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PROGRAMAR UNA REUNI\u00d3N<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Paula y S\u00e9rgio Quinta Redolho de Cima \u2015 Mayo de 2022. Programe una reuni\u00f3n y cu\u00e9ntenos un poco m\u00e1s al respecto.<\/p>","protected":false},"featured_media":9434,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","project-cat":[251],"class_list":["post-10588","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","project-cat-minimalistas"],"acf":[],"_links":{"self":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/portfolio\/10588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/comments?post=10588"}],"version-history":[{"count":5,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/portfolio\/10588\/revisions"}],"predecessor-version":[{"id":36775,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/portfolio\/10588\/revisions\/36775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/media\/9434"}],"wp:attachment":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/media?parent=10588"}],"wp:term":[{"taxonomy":"project-cat","embeddable":true,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/project-cat?post=10588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}