{"id":35332,"date":"2025-12-05T17:49:05","date_gmt":"2025-12-05T17:49:05","guid":{"rendered":"https:\/\/pergaminho.design\/?page_id=35332"},"modified":"2026-03-26T14:44:45","modified_gmt":"2026-03-26T14:44:45","slug":"caja-de-anillos","status":"publish","type":"page","link":"https:\/\/pergaminho.design\/es\/estacion-de-bodas\/caja-de-anillos\/","title":{"rendered":"Caja para alianzas"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"35332\" class=\"elementor elementor-35332\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-bdd9ad8 wd-section-stretch e-flex e-con-boxed e-con e-parent\" data-id=\"bdd9ad8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7262523 elementor-widget elementor-widget-heading\" data-id=\"7262523\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Caja para alianzas<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-a36c336 e-flex e-con-boxed e-con e-parent\" data-id=\"a36c336\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dcc132c e-con-full e-flex e-con e-child\" data-id=\"dcc132c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1eb292c wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"1eb292c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xxl\">Caja para alianzas<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b543ff elementor-widget elementor-widget-wd_text_block\" data-id=\"3b543ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>La caja para anillos es un elemento fundamental para tu gran d\u00eda, ya que ofrece un lugar seguro y elegante para los anillos que simbolizan la uni\u00f3n de la pareja. Nuestras cajas est\u00e1n cuidadosamente elaboradas y personalizadas, convirti\u00e9ndose en un recuerdo imborrable de este momento tan especial.<\/p><p>Puedes elegir entre una variedad de materiales, desde madera para los verdaderos amantes del estilo r\u00fastico, hasta terciopelo para aquellos que prefieren a\u00f1adir un toque m\u00e1s elegante y sofisticado a su gran d\u00eda.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-119b9f1 elementor-widget__width-auto elementor-align-left elementor-widget elementor-widget-button\" data-id=\"119b9f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pergaminho.design\/es\/solicita-un-presupuesto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SOLICITE UN PRESUPUESTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d18898 e-con-full e-flex e-con e-child\" data-id=\"5d18898\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67de2b3 elementor-widget elementor-widget-image\" data-id=\"67de2b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1666\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/056_0466.jpg\" class=\"attachment-full size-full wp-image-30320\" alt=\"Portador de anillos con caja de madera para anillos.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/056_0466.jpg 2500w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/056_0466-300x200.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/056_0466-1024x682.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/056_0466-768x512.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/056_0466-1536x1024.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/056_0466-2048x1365.jpg 2048w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/056_0466-18x12.jpg 18w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/056_0466-1320x880.jpg 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/056_0466-1000x666.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/056_0466-150x100.jpg 150w\" sizes=\"auto, (max-width: 2500px) 100vw, 2500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f01e2d9 e-con-full e-flex e-con e-child\" data-id=\"f01e2d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccd440b elementor-widget elementor-widget-image\" data-id=\"ccd440b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1666\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/057_0489.jpg\" class=\"attachment-full size-full wp-image-30321\" alt=\"Caja de madera para anillos con cojines de arpillera tejidos con cordel natural.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/057_0489.jpg 2500w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/057_0489-300x200.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/057_0489-1024x682.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/057_0489-768x512.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/057_0489-1536x1024.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/057_0489-2048x1365.jpg 2048w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/057_0489-18x12.jpg 18w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/057_0489-1320x880.jpg 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/057_0489-1000x666.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/057_0489-150x100.jpg 150w\" sizes=\"auto, (max-width: 2500px) 100vw, 2500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-e51a3fb e-flex e-con-boxed e-con e-parent\" data-id=\"e51a3fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f19d07 elementor-widget elementor-widget-heading\" data-id=\"2f19d07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Colecci\u00f3n inspiradora<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-1af6407 wd-section-stretch-content e-flex e-con-boxed e-con e-parent\" data-id=\"1af6407\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c31815a e-con-full e-flex e-con e-child\" data-id=\"c31815a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cf5f3b elementor-widget elementor-widget-image\" data-id=\"4cf5f3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1600\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-07-08-at-00.42.42-2.jpeg\" class=\"attachment-full size-full wp-image-34898\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-07-08-at-00.42.42-2.jpeg 1200w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-07-08-at-00.42.42-2-225x300.jpeg 225w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-07-08-at-00.42.42-2-768x1024.jpeg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-07-08-at-00.42.42-2-1152x1536.jpeg 1152w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-07-08-at-00.42.42-2-9x12.jpeg 9w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-07-08-at-00.42.42-2-1000x1333.jpeg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-07-08-at-00.42.42-2-150x200.jpeg 150w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8e6a77 elementor-widget elementor-widget-image\" data-id=\"b8e6a77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1643\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/0171-scaled.jpg\" class=\"attachment-full size-full wp-image-31728\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/0171-scaled.jpg 2560w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/0171-300x193.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/0171-1024x657.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/0171-768x493.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/0171-1536x986.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/0171-2048x1314.jpg 2048w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/0171-18x12.jpg 18w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/0171-1320x847.jpg 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/0171-1000x642.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/0171-150x96.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bf3414 e-con-full e-flex e-con e-child\" data-id=\"3bf3414\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdd01cf elementor-widget elementor-widget-image\" data-id=\"fdd01cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/ATM_8666.jpg\" class=\"attachment-full size-full wp-image-34895\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/ATM_8666.jpg 2048w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/ATM_8666-300x200.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/ATM_8666-1024x683.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/ATM_8666-768x512.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/ATM_8666-1536x1024.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/ATM_8666-18x12.jpg 18w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/ATM_8666-1320x880.jpg 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/ATM_8666-1000x667.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/ATM_8666-150x100.jpg 150w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94fda8f elementor-widget elementor-widget-image\" data-id=\"94fda8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/IMG_0103-scaled.jpg\" class=\"attachment-full size-full wp-image-30324\" alt=\"Caja de cart\u00f3n de terciopelo beige\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/IMG_0103-scaled.jpg 1920w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/IMG_0103-225x300.jpg 225w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/IMG_0103-768x1024.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/IMG_0103-1152x1536.jpg 1152w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/IMG_0103-1536x2048.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/IMG_0103-9x12.jpg 9w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/IMG_0103-1320x1760.jpg 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/IMG_0103-1000x1333.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/IMG_0103-150x200.jpg 150w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c193a6 e-con-full e-flex e-con e-child\" data-id=\"6c193a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc08d0d elementor-widget elementor-widget-image\" data-id=\"dc08d0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/0052-scaled.jpg\" class=\"attachment-full size-full wp-image-34894\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/0052-scaled.jpg 1707w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/0052-200x300.jpg 200w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/0052-683x1024.jpg 683w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/0052-768x1152.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/0052-1024x1536.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/0052-1365x2048.jpg 1365w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/0052-8x12.jpg 8w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/0052-1320x1980.jpg 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/0052-1000x1500.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/0052-150x225.jpg 150w\" sizes=\"auto, (max-width: 1707px) 100vw, 1707px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-067f26b elementor-widget elementor-widget-image\" data-id=\"067f26b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/0188-scaled.jpg\" class=\"attachment-full size-full wp-image-30322\" alt=\"Caja de madera para anillos con cojines de arpillera tejidos con cordel natural.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/0188-scaled.jpg 2560w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/0188-300x200.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/0188-1024x683.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/0188-768x512.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/0188-1536x1024.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/0188-2048x1365.jpg 2048w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/0188-18x12.jpg 18w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/0188-1320x880.jpg 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/0188-1000x667.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/0188-150x100.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1136d3b e-con-full e-flex e-con e-child\" data-id=\"1136d3b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65eae37 elementor-widget elementor-widget-image\" data-id=\"65eae37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/EDIT6385-scaled.jpg\" class=\"attachment-full size-full wp-image-30323\" alt=\"Caja de cart\u00f3n de terciopelo rojo\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/EDIT6385-scaled.jpg 2560w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/EDIT6385-300x200.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/EDIT6385-1024x683.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/EDIT6385-768x512.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/EDIT6385-1536x1024.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/EDIT6385-2048x1366.jpg 2048w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/EDIT6385-18x12.jpg 18w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/EDIT6385-1320x880.jpg 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/EDIT6385-1000x667.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/EDIT6385-150x100.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc01d1a elementor-widget elementor-widget-image\" data-id=\"cc01d1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1366\" height=\"2048\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2024-07-30-at-16.52.02.jpeg\" class=\"attachment-full size-full wp-image-34896\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2024-07-30-at-16.52.02.jpeg 1366w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2024-07-30-at-16.52.02-200x300.jpeg 200w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2024-07-30-at-16.52.02-683x1024.jpeg 683w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2024-07-30-at-16.52.02-768x1151.jpeg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2024-07-30-at-16.52.02-1025x1536.jpeg 1025w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2024-07-30-at-16.52.02-8x12.jpeg 8w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2024-07-30-at-16.52.02-1320x1979.jpeg 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2024-07-30-at-16.52.02-1000x1499.jpeg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2024-07-30-at-16.52.02-150x225.jpeg 150w\" sizes=\"auto, (max-width: 1366px) 100vw, 1366px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d509c07 elementor-widget elementor-widget-image\" data-id=\"d509c07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/MM_131-scaled.jpg\" class=\"attachment-full size-full wp-image-31598\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/MM_131-scaled.jpg 2560w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/MM_131-300x200.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/MM_131-1024x683.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/MM_131-768x512.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/MM_131-1536x1024.jpg 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/MM_131-2048x1365.jpg 2048w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/MM_131-18x12.jpg 18w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/MM_131-1320x880.jpg 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/MM_131-1000x667.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/MM_131-150x100.jpg 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-04b9e91 e-con-full e-flex e-con e-child\" data-id=\"04b9e91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-957dfe3 elementor-widget elementor-widget-image\" data-id=\"957dfe3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"2560\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/IMG_3300-scaled.jpg\" class=\"attachment-full size-full wp-image-31597\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/IMG_3300-scaled.jpg 1440w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/IMG_3300-169x300.jpg 169w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/IMG_3300-576x1024.jpg 576w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/IMG_3300-768x1365.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/IMG_3300-864x1536.jpg 864w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/IMG_3300-1152x2048.jpg 1152w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/IMG_3300-7x12.jpg 7w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/IMG_3300-1320x2347.jpg 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/IMG_3300-1000x1778.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/IMG_3300-150x267.jpg 150w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a5329a elementor-widget elementor-widget-image\" data-id=\"7a5329a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2874\" height=\"1918\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/Screenshot-2024-03-18-at-12.22.36.png\" class=\"attachment-full size-full wp-image-30319\" alt=\"Caja de madera para anillos con cojines de arpillera tejidos con cordel natural.\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/Screenshot-2024-03-18-at-12.22.36.png 2874w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/Screenshot-2024-03-18-at-12.22.36-300x200.png 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/Screenshot-2024-03-18-at-12.22.36-1024x683.png 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/Screenshot-2024-03-18-at-12.22.36-768x513.png 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/Screenshot-2024-03-18-at-12.22.36-1536x1025.png 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/Screenshot-2024-03-18-at-12.22.36-2048x1367.png 2048w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/Screenshot-2024-03-18-at-12.22.36-18x12.png 18w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/Screenshot-2024-03-18-at-12.22.36-1320x881.png 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/Screenshot-2024-03-18-at-12.22.36-1000x667.png 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/05\/Screenshot-2024-03-18-at-12.22.36-150x100.png 150w\" sizes=\"auto, (max-width: 2874px) 100vw, 2874px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50f281c elementor-widget elementor-widget-image\" data-id=\"50f281c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2866\" height=\"1912\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/Screenshot-2024-03-18-at-12.24.30.png\" class=\"attachment-full size-full wp-image-31729\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/Screenshot-2024-03-18-at-12.24.30.png 2866w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/Screenshot-2024-03-18-at-12.24.30-300x200.png 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/Screenshot-2024-03-18-at-12.24.30-1024x683.png 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/Screenshot-2024-03-18-at-12.24.30-768x512.png 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/Screenshot-2024-03-18-at-12.24.30-1536x1025.png 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/Screenshot-2024-03-18-at-12.24.30-2048x1366.png 2048w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/Screenshot-2024-03-18-at-12.24.30-18x12.png 18w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/Screenshot-2024-03-18-at-12.24.30-1320x881.png 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/Screenshot-2024-03-18-at-12.24.30-1000x667.png 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/07\/Screenshot-2024-03-18-at-12.24.30-150x100.png 150w\" sizes=\"auto, (max-width: 2866px) 100vw, 2866px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-f3cb3bd wd-section-stretch e-flex e-con-boxed e-con e-parent\" data-id=\"f3cb3bd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-05fb852 elementor-widget elementor-widget-heading\" data-id=\"05fb852\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo funciona?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-68840b8 e-grid wd-section-stretch e-con-boxed e-con e-parent\" data-id=\"68840b8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-b8ab04f orcamento1 e-flex e-con-boxed e-con e-child\" data-id=\"b8ab04f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0dfe04 elementor-widget elementor-widget-heading\" data-id=\"f0dfe04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">01<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a496f7d elementor-widget elementor-widget-image\" data-id=\"a496f7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1772\" height=\"1772\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_1.png\" class=\"attachment-full size-full wp-image-25736\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_1.png 1772w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_1-300x300.png 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_1-1024x1024.png 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_1-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_1-768x768.png 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_1-1536x1536.png 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_1-12x12.png 12w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_1-1320x1320.png 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_1-1000x1000.png 1000w\" sizes=\"auto, (max-width: 1772px) 100vw, 1772px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6194b66 elementor-widget elementor-widget-image-box\" data-id=\"6194b66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Presupuesto<\/h3><p class=\"elementor-image-box-description\">Comparte con nosotros tus ideas, inspiraciones y sue\u00f1os, y dinos cu\u00e1ntas invitaciones necesitas.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-187643b design1 e-flex e-con-boxed e-con e-child\" data-id=\"187643b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3e0a3b elementor-widget elementor-widget-heading\" data-id=\"a3e0a3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">02<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-decc58c elementor-widget elementor-widget-image\" data-id=\"decc58c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2351\" height=\"2351\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado.png\" class=\"attachment-full size-full wp-image-25741\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado.png 2351w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado-300x300.png 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado-1024x1024.png 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado-768x768.png 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado-1536x1536.png 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado-2048x2048.png 2048w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado-12x12.png 12w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado-2000x2000.png 2000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado-1320x1320.png 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_2_quadrado-1000x1000.png 1000w\" sizes=\"auto, (max-width: 2351px) 100vw, 2351px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28c3b6a elementor-widget elementor-widget-image-box\" data-id=\"28c3b6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Dise\u00f1o<\/h3><p class=\"elementor-image-box-description\">Desarrollamos diversas propuestas personalizadas con el m\u00e1ximo cuidado y creatividad.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-9174aec design1 e-flex e-con-boxed e-con e-child\" data-id=\"9174aec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29a1bf2 elementor-widget elementor-widget-heading\" data-id=\"29a1bf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">03<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-433699f elementor-widget elementor-widget-image\" data-id=\"433699f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1772\" height=\"1772\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_3.png\" class=\"attachment-full size-full wp-image-25735\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_3.png 1772w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_3-300x300.png 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_3-1024x1024.png 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_3-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_3-768x768.png 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_3-1536x1536.png 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_3-12x12.png 12w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_3-1320x1320.png 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_3-1000x1000.png 1000w\" sizes=\"auto, (max-width: 1772px) 100vw, 1772px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47efcc5 elementor-widget elementor-widget-image-box\" data-id=\"47efcc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Producci\u00f3n<\/h3><p class=\"elementor-image-box-description\">Utilizamos diversas t\u00e9cnicas de impresi\u00f3n que contribuyen a enriquecer la textura de las superficies.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-f24251e design1 e-flex e-con-boxed e-con e-child\" data-id=\"f24251e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46b203e elementor-widget elementor-widget-heading\" data-id=\"46b203e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">04<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac88523 elementor-widget elementor-widget-image\" data-id=\"ac88523\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1772\" height=\"1772\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_4.png\" class=\"attachment-full size-full wp-image-25734\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_4.png 1772w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_4-300x300.png 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_4-1024x1024.png 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_4-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_4-768x768.png 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_4-1536x1536.png 1536w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_4-12x12.png 12w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_4-1320x1320.png 1320w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/Icom_4-1000x1000.png 1000w\" sizes=\"auto, (max-width: 1772px) 100vw, 1772px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d24cc87 elementor-widget elementor-widget-image-box\" data-id=\"d24cc87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Entrega<\/h3><p class=\"elementor-image-box-description\">Venga a nuestro estudio a recoger sus invitaciones terminadas, o se las enviaremos a su direcci\u00f3n.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-4d61aca wd-section-stretch e-flex e-con-boxed e-con e-parent\" data-id=\"4d61aca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ed603d elementor-widget__width-auto elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"6ed603d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pergaminho.design\/es\/solicita-un-presupuesto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SOLICITE UN PRESUPUESTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-c1a0aba e-flex e-con-boxed e-con e-parent\" data-id=\"c1a0aba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5279ac1 e-con-full e-flex e-con e-child\" data-id=\"5279ac1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f8eed7 elementor-widget elementor-widget-image\" data-id=\"2f8eed7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"8192\" height=\"5464\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/1-1.jpg\" class=\"attachment-full size-full wp-image-23990\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/1-1.jpg 8192w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/1-1-150x100.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/04\/1-1-1000x667.jpg 1000w\" sizes=\"auto, (max-width: 8192px) 100vw, 8192px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14e048d e-con-full e-flex e-con e-child\" data-id=\"14e048d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ccee34 elementor-widget elementor-widget-image\" data-id=\"9ccee34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1277\" height=\"1079\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586.jpg\" class=\"attachment-full size-full wp-image-22538\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586.jpg 1277w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-150x127.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-1000x845.jpg 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-300x253.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-1024x865.jpg 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-768x649.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/4-1-1-e1711378497586-14x12.jpg 14w\" sizes=\"auto, (max-width: 1277px) 100vw, 1277px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c73c349 e-con-full e-flex e-con e-child\" data-id=\"c73c349\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-164e7a9 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"164e7a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xxl\">Programar una reuni\u00f3n<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7759c2 elementor-widget elementor-widget-wd_text_block\" data-id=\"c7759c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<h5>Estamos a su disposici\u00f3n para asesorarle en la concepci\u00f3n, el dise\u00f1o y la producci\u00f3n de sus invitaciones de boda, bautizo, comuni\u00f3n u otros eventos.<\/h5><p>Creemos que es fundamental conversar para comprender mejor sus ideas y presentarle las soluciones que tenemos disponibles para el dise\u00f1o de sus invitaciones. Podemos reunirnos por videollamada o, si lo prefiere, en persona.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7870015 elementor-widget__width-auto elementor-align-left elementor-widget elementor-widget-button\" data-id=\"7870015\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pergaminho.design\/es\/programar-una-reunion\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PROGRAMAR UNA REUNI\u00d3N<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-155d33f e-flex e-con-boxed e-con e-parent\" data-id=\"155d33f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-73dfc27 e-flex e-con-boxed e-con e-child\" data-id=\"73dfc27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dcaa557 elementor-widget__width-auto wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"dcaa557\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xxl\">Otras colecciones de papeler\u00eda<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f09e38b elementor-widget__width-auto elementor-widget elementor-widget-wd_button\" data-id=\"f09e38b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-left\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-round btn-size-large btn-color-white btn-icon-pos-right\"  href=\"https:\/\/pergaminho.design\/es\/estacion-de-bodas\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tM\u00e1s inspiraci\u00f3n\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t<span class=\"wd-btn-icon\">\n\t\t\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2023\/04\/wd-furniture-long-arrow-black.svg\" title=\"wd-furniture-long-arrow-black\" loading=\"lazy\" width=\"16\" height=\"17\">\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84ea7ad e-grid e-con-full e-con e-parent\" data-id=\"84ea7ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1c6ea23 e-con-full e-flex e-con e-child\" data-id=\"1c6ea23\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3ca04b elementor-widget__width-initial elementor-widget elementor-widget-wd_infobox\" data-id=\"c3ca04b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-right box-style-bg-hover color-scheme-light wd-items-bottom color-scheme-hover-light\">\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-m\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tMen\u00fa\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pergaminho.design\/es\/estacion-de-bodas\/menu\/\" class=\"wd-info-box-link wd-fill\" aria-label=\"Enlace al cuadro informativo\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-247c31f e-con-full e-flex e-con e-child\" data-id=\"247c31f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-923f4ce elementor-widget__width-initial elementor-widget elementor-widget-wd_infobox\" data-id=\"923f4ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-right box-style-bg-hover color-scheme-light wd-items-bottom color-scheme-hover-light\">\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-m\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tMarcador de la mesa\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pergaminho.design\/es\/estacion-de-bodas\/marcador-de-mesa\/\" class=\"wd-info-box-link wd-fill\" aria-label=\"Enlace al cuadro informativo\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-922833f e-con-full e-flex e-con e-child\" data-id=\"922833f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46831de elementor-widget__width-initial elementor-widget elementor-widget-wd_infobox\" data-id=\"46831de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-right box-style-bg-hover color-scheme-light wd-items-bottom color-scheme-hover-light\">\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-m\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tPlano de asientos\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pergaminho.design\/es\/estacion-de-bodas\/plano-de-asientos\/\" class=\"wd-info-box-link wd-fill\" aria-label=\"Enlace al cuadro informativo\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac0f0fc elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-wd_infobox\" data-id=\"ac0f0fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-right box-style-bg-hover color-scheme-light wd-items-bottom color-scheme-hover-light\">\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-m\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tMisal\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pergaminho.design\/es\/estacion-de-bodas\/misal\/\" class=\"wd-info-box-link wd-fill\" aria-label=\"Enlace al cuadro informativo\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32813b0 e-con-full e-flex e-con e-child\" data-id=\"32813b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-581f7bf elementor-widget__width-initial elementor-widget elementor-widget-wd_infobox\" data-id=\"581f7bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-right box-style-bg-hover color-scheme-light wd-items-bottom color-scheme-hover-light\">\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-m\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tLibro de Honor\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pergaminho.design\/es\/estacion-de-bodas\/libro-de-honor\/\" class=\"wd-info-box-link wd-fill\" aria-label=\"Enlace al cuadro informativo\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-8697da7 wd-section-stretch e-flex e-con-boxed e-con e-parent\" data-id=\"8697da7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bb1809a e-con-full e-flex e-con e-child\" data-id=\"bb1809a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d9a34fc wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"d9a34fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xxl\">Testimonios<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbb7dd3 elementor-widget elementor-widget-wd_testimonials\" data-id=\"fbb7dd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"testimonials testimon-style-boxed  color-scheme- testimon-with-rating testimon-align-left wd-carousel-container\" id=\"carousel-2505\">\n\t\t\t\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\n\t\t\t<div class=\"wd-carousel wd-grid\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:1;--wd-gap-lg:30px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Cate-Gouveia-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p>Para m\u00ed, Pergaminho fue uno de los mejores descubrimientos de 2020, el a\u00f1o de mi boda, y fue con Pergaminho que realic\u00e9 todo lo que hab\u00eda idealizado para este d\u00eda inolvidable en nuestras vidas.\u00a0<\/p>\n\t\t\t<footer>\n\t\t\t\tCatarina Gouveia\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tLisboa, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_01-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_01-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_01-600x600.png 600w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\u201c&quot;\u00a1CHICOS! \u00a1Gracias por todo ayer! \u00a1Sois un equipo incre\u00edble! Todo fue perfecto y no podr\u00edamos haber pedido m\u00e1s \ud83e\udd0d \u00a1Muchas, muchas gracias!&quot;\u201d\n\t\t\t<footer>\n\t\t\t\tIn\u00eas Brusselmans\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tLisboa, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_02-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p class=\"p1\">\u201c&quot;\u00a1Me encant\u00f3! \u00a1Todo era tan bonito! \u00a1Me gustaron especialmente las invitaciones de Ariel y Santi!&quot;<br \/>A todos les encant\u00f3. \u00a1Much\u00edsimas gracias!\u201d<\/p>\n\t\t\t<footer>\n\t\t\t\tLiliana Filipa\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tLisboa, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.35.46-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.35.46-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.35.46-1000x1000.png 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.35.46-1200x1200.png 1200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p>Las invitaciones son incre\u00edbles, mucho mejores de lo que hab\u00edamos imaginado. <br \/>Estuvieron atentos a todos nuestros gustos y no se les escap\u00f3 ni un detalle. <br \/>Est\u00e1bamos completamente abrumados. <br \/>Muchas gracias!<\/p>\n\t\t\t<footer>\n\t\t\t\tLia Magalh\u00e3es\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tLousada, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.40.19-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.40.19-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.40.19-1000x1000.png 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.40.19-1200x1200.png 1200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p>Trabajo de excelente calidad. La comunicaci\u00f3n fue super org\u00e1nica y f\u00e1cil de establecer. Aparte de eso, el trabajo se llev\u00f3 a cabo con rapidez, con cuidado a\u00f1adido porque fue enviado a la Regi\u00f3n Aut\u00f3noma de Madeira. Muy recomendable!!!!<\/p>\n\t\t\t<footer>\n\t\t\t\tLic\u00ednia Fernandes\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tMadeira, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.44.09-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.44.09-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.44.09-1000x1000.png 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Screenshot-2023-01-02-at-14.44.09-1200x1200.png 1200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p>Nunca tuvimos dudas sobre nuestra elecci\u00f3n.<br \/>Fuisteis la primera opci\u00f3n que consideramos y \u00a1no podr\u00edamos estar m\u00e1s contentos con el resultado final de nuestras invitaciones! Somos fans de vuestro trabajo y os recomendar\u00edamos sin dudarlo!<\/p>\n\t\t\t<footer>\n\t\t\t\tCatarina Novo\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tOporto, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Andreia-Joao-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\tNuestra primera elecci\u00f3n no pudo ser mejor.\nProfesionalidad desde el primer momento y cada detalle pensado hasta el m\u00e1s m\u00ednimo detalle.<br><br>\nSe lo recomiendo.\n\t\t\t<footer>\n\t\t\t\tAndreia A.\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tLisboa, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Catia-Melo-Duarte-1-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p>Las invitaciones eran simplemente divinas y Joana estuvo s\u00faper disponible, siempre atenta a cada detalle. <br \/>El resultado final nos sorprendi\u00f3, \u00a1todo era a\u00fan m\u00e1s bonito de lo que hab\u00edamos imaginado!<\/p>\n\t\t\t<footer>\n\t\t\t\tC\u00e1tia Duarte\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tLisboa, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-1000x993.png 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-300x298.png 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-1024x1017.png 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-768x763.png 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1.png 1178w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p>Hicieron un trabajo original y muy profesional. <br \/>Estuvieron atentos a cada detalle, fueron extremadamente flexibles, amables y competentes. <br \/>Un trabajo excelente! Felicidades!<\/p>\n\t\t\t<footer>\n\t\t\t\tPaula Catarina\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tFelgueiras, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_03-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_03-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_03-11x12.png 11w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p>\"Nos encanta c\u00f3mo quedaron nuestras invitaciones! Joana y C\u00e1tia fueron s\u00faper serviciales y estuvieron disponibles desde el principio y siempre abiertas a nuestras preguntas y cambios.\"<\/p>\n\t\t\t<footer>\n\t\t\t\tRaquel Vaz Garrido\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tLisboa, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_04-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_04-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_04-13x12.png 13w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p>\"Absolutely Stupendous!!!<br \/>La capacidad de comunicarse, comprender y satisfacer las necesidades del cliente es absolutamente fascinante. Todas nuestras peticiones fueron atendidas y ejecutadas con una profesionalidad excepcional. Las invitaciones son indescriptibles. \u00bfY los regalitos para los invitados? \u00a1Preciosos! \u00bfY el kit para la resaca? \u00a1Simplemente genial!\u201d<\/p>\n\t\t\t<footer>\n\t\t\t\tRita Fernandes\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tBraga, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_05-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_05-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_05-11x12.png 11w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p>\"Un equipo muy atento que supo cumplir nuestras ideas y superar nuestras expectativas. Las invitaciones quedaron perfectas! Gracias por todo\".<\/p>\n\t\t\t<footer>\n\t\t\t\tMagda Rebanda\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tBragan\u00e7a, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_06-150x150.jpg\" class=\"testimonial-avatar-image\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_06-150x150.jpg 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_06-300x298.jpg 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_06-768x763.jpg 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_06-12x12.jpg 12w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_06-600x600.jpg 600w, https:\/\/pergaminho.design\/wp-content\/uploads\/2024\/03\/Testemunho_06.jpg 960w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p class=\"p1\">\"Recomiendo el trabajo de Pergaminho. Siempre fueron muy profesionales, disponibles y receptivos a todas nuestras peticiones. Quedamos muy contentos con el resultado final\".<\/p><p><br \/><br \/><\/p>\n\t\t\t<footer>\n\t\t\t\tC\u00e1tia Jorge\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tCoimbra, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"testimonial wd-carousel-item\">\n\t<div class=\"testimonial-inner\">\n\t\t\t\t\t<div class=\"testimonial-avatar\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-150x150.png\" class=\"testimonial-avatar-image\" alt=\"\" srcset=\"https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-150x150.png 150w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-1000x993.png 1000w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-300x298.png 300w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-1024x1017.png 1024w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1-768x763.png 768w, https:\/\/pergaminho.design\/wp-content\/uploads\/2021\/10\/Paula-Catarina-Sergio-1.png 1178w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"testimonial-content\">\n\t\t\t<div class=\"testimonial-rating\">\n\t\t\t\t<span class=\"star-rating\">\n\t\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<p class=\"p1\">\u201cNo me arrepiento ni un instante de haber elegido a Pergaminho para dise\u00f1ar nuestras invitaciones de boda y tambi\u00e9n las invitaciones para los invitados. Todos est\u00e1n encantados con las invitaciones, soy una novia muy orgullosa. \u00a1Much\u00edsimas gracias por formar parte de nuestro sue\u00f1o como si fuera el vuestro!\"<\/p>\n\t\t\t<footer>\n\t\t\t\tDiana Soeiro\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\tAmarante, Portugal\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/footer>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<link rel=\"stylesheet\" id=\"wd-collapsible-content-css\" href=\"https:\/\/pergaminho.design\/wp-content\/themes\/woodmart\/css\/parts\/elem-opt-collapsible-content.min.css?ver=8.4.1\" type=\"text\/css\" media=\"all\" \/> \t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-471a2cb wd-collapsible-content e-flex e-con-boxed e-con e-parent\" data-id=\"471a2cb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e1afa2 elementor-widget elementor-widget-wd_text_block\" data-id=\"6e1afa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p><span style=\"font-weight: 400;\">A\u00f1ade un toque de elegancia y encanto a tu gran d\u00eda con nuestras impresionantes cajas para anillos personalizadas. <\/span><span style=\"font-weight: 400;\">En Pergaminho, ofrecemos una colecci\u00f3n exclusiva de cajas de terciopelo y madera, dise\u00f1adas para complementar a la perfecci\u00f3n su boda. <\/span><\/p><p><span style=\"font-weight: 400;\">Nuestras cajas para anillos est\u00e1n meticulosamente elaboradas con materiales de alta calidad, como terciopelo lujoso y madera cl\u00e1sica. Cada detalle se trabaja con esmero para garantizar no solo belleza, sino tambi\u00e9n durabilidad, convirti\u00e9ndolas en un elemento encantador para su evento.<\/span><\/p><p><span style=\"font-weight: 400;\">Personaliza tu caja para anillos para que combine con el estilo y la tem\u00e1tica de tu evento. Ya sea una elegante caja de terciopelo suave o una encantadora caja r\u00fastica de madera, estamos aqu\u00ed para hacer realidad tu visi\u00f3n. A\u00f1ade detalles personalizados como iniciales, fechas o incluso un mensaje especial para que tu caja sea verdaderamente \u00fanica. Adem\u00e1s de ser un hermoso accesorio para tu d\u00eda especial, nuestras cajas para anillos se convierten en un preciado recuerdo para el futuro.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">En tu boda, no dejes nada al azar. Celebra el amor y la uni\u00f3n con un estuche para anillos personalizado de Pergaminho. Cont\u00e1ctanos para encargar tu estuche y a\u00f1adir un toque de sofisticaci\u00f3n y significado a tu evento.<\/span><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50ffeef elementor-widget elementor-widget-wd_button\" data-id=\"50ffeef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-left wd-collapsible-button\" >\n\t\t\t<a class=\"btn btn-style-link btn-shape- btn-size-default btn-color-primary btn-icon-pos-right\"  href=\"#\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tLeer m\u00e1s\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Caja para anillos La caja para anillos es un elemento fundamental para tu gran d\u00eda, que ofrece<\/p>","protected":false},"author":1,"featured_media":9774,"parent":996,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-35332","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/pages\/35332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/comments?post=35332"}],"version-history":[{"count":5,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/pages\/35332\/revisions"}],"predecessor-version":[{"id":36418,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/pages\/35332\/revisions\/36418"}],"up":[{"embeddable":true,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/pages\/996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/media\/9774"}],"wp:attachment":[{"href":"https:\/\/pergaminho.design\/es\/wp-json\/wp\/v2\/media?parent=35332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}